{"id":11352,"date":"2020-10-18T15:16:31","date_gmt":"2020-12-26T12:22:51","guid":{"rendered":"https:\/\/masdors.ch\/index.php\/produit\/bier-schuetze-fuer-den-aussenbereich\/"},"modified":"2020-12-26T13:22:56","modified_gmt":"2020-12-26T12:22:56","slug":"schutze-a-bier-fur-lexier","status":"publish","type":"product","link":"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de","title":{"rendered":"Bier-Sch\u00fctze f\u00fcr den Au\u00dfenbereich"},"content":{"rendered":"<p style=\"text-align: center;\">Eine Outdoor-K\u00fcche f\u00fcr Bierliebhaber ist einfach nicht komplett ohne einen Druckbierbar.<\/p>\n<p style=\"text-align: center;\">Mit dieser Bier-Sch\u00fctzin, bringen Sie ein Plus auf Ihre Terrasse auf den Partys mit Freunden und Familie.<\/p>\n<p style=\"text-align: center;\"><strong>Merkmale:<\/strong><\/p>\n<p style=\"text-align: center;\">NSF-zertifiziert<br \/>\nLED-Innenbeleuchtung<br \/>\nAus nur einem Wasserhahn<br \/>\n140 lts mit einfachem gebogenen Wasserhahn, Einzelauflage<br \/>\nBau aus Edelstahl 304<br \/>\nT\u00fcr mit umkehrbarem selbstt\u00e4tigen Schlie\u00dfverschluss<br \/>\nEntworfen, um autonom oder eingelassen zu sein<br \/>\nTemperatur von 10 bis 0 Grad C<br \/>\nGelistet ETL, CETL, DOE, NSF<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/masdors.ch\/wp-content\/uploads\/2020\/10\/Tireuse-a-biere-cat-17900-1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF-Cat<\/a>                            <a href=\"http:\/\/masdors.ch\/wp-content\/uploads\/2020\/10\/Tireuse-a-biere-dim-17900.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF-Dim<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Artikelnummer:<\/strong><\/p>\n<p>17900<\/p>\n","protected":false},"featured_media":2705,"template":"","meta":[],"product_cat":[234],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bier-Sch\u00fctze f\u00fcr den Au\u00dfenbereich - Masdors - Cuisines ext\u00e9rieurs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bier-Sch\u00fctze f\u00fcr den Au\u00dfenbereich - Masdors - Cuisines ext\u00e9rieurs\" \/>\n<meta property=\"og:description\" content=\"Artikelnummer: 17900\" \/>\n<meta property=\"og:url\" content=\"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de\" \/>\n<meta property=\"og:site_name\" content=\"Masdors - Cuisines ext\u00e9rieurs\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-26T12:22:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/masdors.ch\/wp-content\/uploads\/2020\/10\/Tireuse-a-biere-17900CEa-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1491\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de\",\"url\":\"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de\",\"name\":\"Bier-Sch\u00fctze f\u00fcr den Au\u00dfenbereich - Masdors - Cuisines ext\u00e9rieurs\",\"isPartOf\":{\"@id\":\"https:\/\/masdors.ch\/#website\"},\"datePublished\":\"2020-12-26T12:22:51+00:00\",\"dateModified\":\"2020-12-26T12:22:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/masdors.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\/\/masdors.ch\/index.php\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bier-Sch\u00fctze f\u00fcr den Au\u00dfenbereich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/masdors.ch\/#website\",\"url\":\"https:\/\/masdors.ch\/\",\"name\":\"Masdors - Cuisines ext\u00e9rieurs\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/masdors.ch\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/masdors.ch\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/masdors.ch\/#organization\",\"name\":\"Masdors - Cuisines ext\u00e9rieurs\",\"url\":\"https:\/\/masdors.ch\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/masdors.ch\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/masdors.ch\/wp-content\/uploads\/2020\/09\/Masdors_Logo-01x.png\",\"contentUrl\":\"https:\/\/masdors.ch\/wp-content\/uploads\/2020\/09\/Masdors_Logo-01x.png\",\"width\":223,\"height\":63,\"caption\":\"Masdors - Cuisines ext\u00e9rieurs\"},\"image\":{\"@id\":\"https:\/\/masdors.ch\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bier-Sch\u00fctze f\u00fcr den Au\u00dfenbereich - Masdors - Cuisines ext\u00e9rieurs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/","og_locale":"fr_FR","og_type":"article","og_title":"Bier-Sch\u00fctze f\u00fcr den Au\u00dfenbereich - Masdors - Cuisines ext\u00e9rieurs","og_description":"Artikelnummer: 17900","og_url":"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de","og_site_name":"Masdors - Cuisines ext\u00e9rieurs","article_modified_time":"2020-12-26T12:22:56+00:00","og_image":[{"width":1491,"height":2560,"url":"https:\/\/masdors.ch\/wp-content\/uploads\/2020\/10\/Tireuse-a-biere-17900CEa-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de","url":"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de","name":"Bier-Sch\u00fctze f\u00fcr den Au\u00dfenbereich - Masdors - Cuisines ext\u00e9rieurs","isPartOf":{"@id":"https:\/\/masdors.ch\/#website"},"datePublished":"2020-12-26T12:22:51+00:00","dateModified":"2020-12-26T12:22:56+00:00","breadcrumb":{"@id":"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/masdors.ch\/index.php\/produit\/schutze-a-bier-fur-lexier\/?lang=de#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/masdors.ch\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/masdors.ch\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Bier-Sch\u00fctze f\u00fcr den Au\u00dfenbereich"}]},{"@type":"WebSite","@id":"https:\/\/masdors.ch\/#website","url":"https:\/\/masdors.ch\/","name":"Masdors - Cuisines ext\u00e9rieurs","description":"","publisher":{"@id":"https:\/\/masdors.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/masdors.ch\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/masdors.ch\/#organization","name":"Masdors - Cuisines ext\u00e9rieurs","url":"https:\/\/masdors.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/masdors.ch\/#\/schema\/logo\/image\/","url":"https:\/\/masdors.ch\/wp-content\/uploads\/2020\/09\/Masdors_Logo-01x.png","contentUrl":"https:\/\/masdors.ch\/wp-content\/uploads\/2020\/09\/Masdors_Logo-01x.png","width":223,"height":63,"caption":"Masdors - Cuisines ext\u00e9rieurs"},"image":{"@id":"https:\/\/masdors.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/masdors.ch\/index.php\/wp-json\/wp\/v2\/product\/11352"}],"collection":[{"href":"https:\/\/masdors.ch\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/masdors.ch\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masdors.ch\/index.php\/wp-json\/wp\/v2\/media\/2705"}],"wp:attachment":[{"href":"https:\/\/masdors.ch\/index.php\/wp-json\/wp\/v2\/media?parent=11352"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/masdors.ch\/index.php\/wp-json\/wp\/v2\/product_cat?post=11352"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/masdors.ch\/index.php\/wp-json\/wp\/v2\/product_tag?post=11352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}